{"id":1069,"date":"2018-12-08T10:00:44","date_gmt":"2018-12-08T10:00:44","guid":{"rendered":"https:\/\/www.support-together.de\/page\/?p=1069"},"modified":"2018-12-07T21:45:00","modified_gmt":"2018-12-07T21:45:00","slug":"fanclubweihnachtsfeier-unseres-ballspielvereins-aus-dortmund-2018","status":"publish","type":"post","link":"https:\/\/www.support-together.de\/page\/fanclubweihnachtsfeier-unseres-ballspielvereins-aus-dortmund-2018\/","title":{"rendered":"Fanclubweihnachtsfeier unseres Ballspielvereins aus Dortmund 2018"},"content":{"rendered":"<p>Ein wundersch\u00f6ner Abend sollte es werden dieser 03.12.2018, \u00a0schlie\u00dflich ist die Vorweihnachtszeit die sch\u00f6nste Zeit im Jahr .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Hinfahrt.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1070 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Hinfahrt.jpeg\" alt=\"\" width=\"750\" height=\"571\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Hinfahrt.jpeg 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Hinfahrt-300x228.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Hinfahrt-394x300.jpeg 394w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Auch im diesem Jahr besuchten wir , der saarl\u00e4ndische BVB Fanclub \u201eSupport Together \u201e vertreten durch Christian Metzner und Michael Eich eins der Highlights aller Fanclubs unseres Ballspielvereins, die BVB Fanclubweihnachtsfeier.<\/p>\n<p>F\u00fcr uns war es das erste mal an der Feier teilzunehmen zu d\u00fcrfen, aber jeder Kilometer war die Vorfreude kaum auszuhalten . Auch das sehr schlechte Wetter und der viele Verkehr auf der Hinfahrt lie\u00dfen unsere Laune nicht verderben \u00a0.<\/p>\n<p>Sind aber p\u00fcnktlich in Dortmund am Westfalenstadion angekommen . Schnell noch einmal eine kleine Shopping Tour durch den Fanshop ,ehe es dann zur Feier ging .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Eich-Westfalenstadion.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1083\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Eich-Westfalenstadion.jpeg\" alt=\"\" width=\"750\" height=\"580\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Eich-Westfalenstadion.jpeg 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Eich-Westfalenstadion-300x232.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Eich-Westfalenstadion-388x300.jpeg 388w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>Als aller erstes machten Wir uns mit der R\u00e4umlichkeit am diesen Abend vertraut. Dies erledigt , \u00a0schnauften wir Kurz durch mit einen k\u00fchlen Getr\u00e4nk .<\/p>\n<p>Dies noch nicht leer getrunken betritt unser ehemalige Spielf\u00fchrer Kehli dem Raum . Wir gingen zu ihm hin und die ersten Borussenfotos wurden geschossen und Autogramm wurden verewigt . Kurz danach um 18.30Uhr wurde die Feier von kein geringen als von unserem Aki Watzke er\u00f6ffnet .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Er\u00f6ffnung-Watze-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1074 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Er\u00f6ffnung-Watze-1.png\" alt=\"\" width=\"750\" height=\"779\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Er\u00f6ffnung-Watze-1.png 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Er\u00f6ffnung-Watze-1-289x300.png 289w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>Als wir danach Teddy versteckt sitzen sahen wurde er auch f\u00fcr das eine oder andere Foto mit Autogramm gebeten .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Teddy.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1075 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Teddy.jpeg\" alt=\"\" width=\"649\" height=\"556\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Teddy.jpeg 649w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Teddy-300x257.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Teddy-350x300.jpeg 350w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/a>Da wir zur Autogrammstunde die zweit.- oder drittletzte Gruppe waren \u00fcberbr\u00fcckten wir die Zeit uns mit \u00a0anderen bekannten Fanclubskollegen zu unterhalten , lernten auch andere neue nette \u00a0Kollege kennen .<\/p>\n<p>Zwischendurch erhofften wir unsere Chance bei der Tombola als gl\u00fccklicher Gewinner heimzufahren . Schnell mussten wir aber feststellen das dass losgl\u00fcck nicht auf unserer Seite war . Knappe 10 Nummer war das beste Ergebnis .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Kehl.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1072 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Kehl.jpeg\" alt=\"\" width=\"717\" height=\"564\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Kehl.jpeg 717w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Kehl-300x236.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Kehl-381x300.jpeg 381w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/a>Irgendwann war es dann soweit und wir durften zur Autogramm Stunde uns anstellen . Wir betraten den Raum und wollten am liebsten die Zeit stehen lassen .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammstunde.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1076 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammstunde.jpeg\" alt=\"\" width=\"732\" height=\"566\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammstunde.jpeg 732w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammstunde-300x232.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammstunde-388x300.jpeg 388w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Delaney.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1080\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Delaney.jpeg\" alt=\"\" width=\"733\" height=\"563\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Delaney.jpeg 733w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Delaney-300x230.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Delaney-391x300.jpeg 391w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Witsel.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1081\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Witsel.jpeg\" alt=\"\" width=\"671\" height=\"569\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Witsel.jpeg 671w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Witsel-300x254.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Witsel-354x300.jpeg 354w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Paco.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1082\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Paco.jpeg\" alt=\"\" width=\"741\" height=\"558\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Paco.jpeg 741w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Paco-300x226.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Eich-Paco-398x300.jpeg 398w\" sizes=\"auto, (max-width: 741px) 100vw, 741px\" \/><\/a><\/p>\n<p>Jeder einzelne Spieler und Trainerstab \u00a0hat sich auf das Dortmund Trikot und auf unseren SuTo-Pulli verewig . Ein Moment der Gl\u00fcckseligkeit f\u00fcr die Ewigkeit .<br \/>\n<a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammpulli.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1077 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammpulli.jpeg\" alt=\"\" width=\"750\" height=\"554\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammpulli.jpeg 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammpulli-300x222.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Autogrammpulli-406x300.jpeg 406w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>Nach der Autogramm Stunde ging es direkt weiter mit der am Autogrammbar wo vereinzelt die Spieler den Zapfhahn auf Hochtouren im Betrieb brachten \u00a0. 1-2 brinkhoff wurden serviert von Paco und Witsel.<\/p>\n<p>Danach bekam Christian im Obergeschoss noch ein Bier serviert von<br \/>\nMo Dahoud.<br \/>\n<a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Dahoud.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1078 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Dahoud.jpeg\" alt=\"\" width=\"750\" height=\"571\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Dahoud.jpeg 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Dahoud-300x228.jpeg 300w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Metze-Dahoud-394x300.jpeg 394w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Ein gelingender Abend ging zu Ende und wir lie\u00dfen den Abend mit den Kollegen von Fanclub Eifel an der Bar Revue passieren bevor wir die R\u00fcckreise antraten . Ein gedenkw\u00fcrdiger Abend ging zu Ende . Einkindsheitstraum ging in Erf\u00fcllung .<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Abschlussfoto.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1079 size-full\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Abschlussfoto.jpeg\" alt=\"\" width=\"491\" height=\"568\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Abschlussfoto.jpeg 491w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Abschlussfoto-259x300.jpeg 259w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><\/a><\/p>\n<p>Heute 1-2 Tage danach wieder ausgeschlafen kommt man aus dem Schw\u00e4rmen nicht mehr raus . Mit breiten Grinsen wird sich auf das DERBY vorbereitet .<\/p>\n<p>Im diesem Sinne w\u00fcnschen wir im gesamten Namen von Support Together allen Borussen\/in , Freunde , Bekannten \u00a0, Verwandten und euren Familien eine sch\u00f6ne und ruhige Weihnachtszeit und einen guten Rutsch ins neue Jahr . Auf ein erfolgreiches Jahr 2019!<\/p>\n<p><a href=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Fanwelt.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1085\" src=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Fanwelt.png\" alt=\"\" width=\"750\" height=\"970\" srcset=\"https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Fanwelt.png 750w, https:\/\/www.support-together.de\/page\/wp-content\/uploads\/2018\/12\/Fanwelt-232x300.png 232w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>So und ab jetzt z\u00e4hlt nur noch eins WIR WOLLEN DEN DERBYSIEG!!<br \/>\nAm Samstag alles geben<\/p>\n<p>Euer Eich und Metzner<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein wundersch\u00f6ner Abend sollte es werden dieser 03.12.2018, \u00a0schlie\u00dflich ist die Vorweihnachtszeit die sch\u00f6nste Zeit im Jahr . Auch im diesem Jahr besuchten wir , der saarl\u00e4ndische BVB Fanclub \u201eSupport Together \u201e vertreten durch Christian Metzner und Michael Eich eins &hellip; <a href=\"https:\/\/www.support-together.de\/page\/fanclubweihnachtsfeier-unseres-ballspielvereins-aus-dortmund-2018\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1069","post","type-post","status-publish","format-standard","hentry","category-berichte"],"_links":{"self":[{"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/posts\/1069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/comments?post=1069"}],"version-history":[{"count":3,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/posts\/1069\/revisions"}],"predecessor-version":[{"id":1087,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/posts\/1069\/revisions\/1087"}],"wp:attachment":[{"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/media?parent=1069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/categories?post=1069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.support-together.de\/page\/wp-json\/wp\/v2\/tags?post=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}